{"id":15,"count":0,"description":"React, Next.js, Vue, Web Performance, State Management &amp; Modern CSS\/TypeScript.","link":"https:\/\/corpolearn.com\/software\/category\/frontend-engineering\/","name":"Frontend Engineering","slug":"frontend-engineering","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/corpolearn.com\/software\/wp-json\/wp\/v2\/categories\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corpolearn.com\/software\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/corpolearn.com\/software\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/corpolearn.com\/software\/wp-json\/wp\/v2\/posts?categories=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}