{"id":18,"count":0,"description":"Tokenization, Embeddings &amp; Transformer Models","link":"https:\/\/corpolearn.com\/dataai\/category\/nlp-text\/","name":"Natural Language Processing","slug":"nlp-text","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/corpolearn.com\/dataai\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corpolearn.com\/dataai\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/corpolearn.com\/dataai\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/corpolearn.com\/dataai\/wp-json\/wp\/v2\/posts?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}